{"id":62537,"date":"2026-03-11T17:38:01","date_gmt":"2026-03-11T16:38:01","guid":{"rendered":"https:\/\/www.eyebody.com\/?p=62537"},"modified":"2026-04-19T14:50:31","modified_gmt":"2026-04-19T12:50:31","slug":"das-natuerliche-sehen-eyebody-online-einfuehrungskurs-4-module","status":"publish","type":"post","link":"https:\/\/staging.eyebody.com\/de\/das-natuerliche-sehen-eyebody-online-einfuehrungskurs-4-module\/","title":{"rendered":"Das nat\u00fcrliche Sehen \u2013 Eyebody Online Einf\u00fchrungskurs"},"content":{"rendered":"<p>von und mit Peter Grunwald, moderiert durch Ursula G\u00e9rard<!--more--><\/p>\n<p>&nbsp;<\/p>\n\n\n<div class=\"seminar-list-wrapper\" style=\"padding: 20px 20px 14px 20px;\">\n<p style=\"text-align: center;\"><strong>Wenn Sie diesen Online-Kurs bereits gekauft haben, melden Sie sich bitte zun\u00e4chst mit Ihrer E-Mail-Adresse und Ihrem Passwort an:<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"#modal-login\" class=\"button\" data-toggle=\"ml-modal\">Anmelden\/Login<\/a>\n<\/div>\n<p>&nbsp;<\/p>\n<h3>Willkommen zum Eyebody Online Einf\u00fchrungskurs<\/h3>\n<p>In diesem Kurs lernen Sie, in welcher Weise es nicht die Augen sind, mit denen Sie sehen, sondern das Gehirn. Aufbauend auf mehr als 30 Jahren Erfahrung wird Peter Grunwald Sie Schritt f\u00fcr Schritt begleiten und in die Welt der nat\u00fcrlichen Verbesserung des Sehens einf\u00fchren. Er zeigt auf, wie flexibel das Funktionieren des Gehirns ist \u2013 und in der Folge davon auch Sehen und Vorstellungsverm\u00f6gen ver\u00e4nderlich sind.<\/p>\n<p><strong>Diesen Online-Kurs k\u00f6nnen Sie in unserem Shop erworben.<\/strong><\/p>\n<p><a class=\"button btn-primary\" href=\"https:\/\/www.eyebody.com\/de\/shop\/das-natuerliche-sehen-eyebody-online-einfuehrungskurs-4-module\/\">Kurs &#8211; Informationen &amp; Buchung<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>von und mit Peter Grunwald, moderiert durch Ursula G\u00e9rard<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-62537","post","type-post","status-publish","format-standard","hentry","category-medienbibliothek-cat"],"_links":{"self":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts\/62537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/comments?post=62537"}],"version-history":[{"count":2,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts\/62537\/revisions"}],"predecessor-version":[{"id":65677,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts\/62537\/revisions\/65677"}],"wp:attachment":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/media?parent=62537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/categories?post=62537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/tags?post=62537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}