{"id":58148,"date":"2024-09-23T17:09:44","date_gmt":"2024-09-23T15:09:44","guid":{"rendered":"https:\/\/www.eyebody.com\/?p=58148"},"modified":"2026-03-27T12:35:28","modified_gmt":"2026-03-27T11:35:28","slug":"6-tage-kurs-hohenfels-juli-2026","status":"publish","type":"post","link":"https:\/\/staging.eyebody.com\/de\/6-tage-kurs-hohenfels-juli-2026\/","title":{"rendered":"6 Tage-Kurs, Schloss Hohenfels \u2013 Juli 2026"},"content":{"rendered":"<p><strong>Sechst\u00e4giger Basis-Intensivkurs mit Peter Grunwald<br \/>\n26. Juli \u2013 \u00a01. August 2026<\/strong><br \/>\nSprache: Deutsch<\/p>\n<p><strong>Seminar-Organisation: <\/strong><br \/>\nAnne Olschewski<br \/>\nTelefon: +49 (0)172 431 86 16<br \/>\nE-Mail: office@eyebody.de<\/p>\n<p><strong>Beginn und Ende des Kurses:<\/strong><br \/>\nKursbeginn am ersten Tag um 17 Uhr<br \/>\nKursende am letzten Tag nach dem Mittagessen, ca. 14:30 Uhr<\/p>\n<p><strong>Seminarort:<\/strong><br \/>\n<a href=\"https:\/\/www.schloss-hohenfels.de\/\" target=\"_blank\" rel=\"noopener\">Tagungszentrum Schloss Hohenfels<\/a>, Schloss Hohenfels 1, 78355 Hohenfels<\/p>\n<p><strong>Kursgeb\u00fchr (zzgl. \u00dcbernachtung\/Vollpension siehe unten):<br \/>\nFr\u00fchbucherpreis bis 31. M\u00e4rz 2026: 849,- \u20ac<br \/>\n<\/strong>danach: 969,- \u20ac<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Dieses Seminar ist ausgebucht.<\/strong><br \/>\n<strong>Wir f\u00fchren eine Warteliste.<\/strong><br \/>\n<\/span><\/p>\n<p><a class=\"button btn-primary\" href=\"https:\/\/www.eyebody.com\/de\/warteliste-eyebody-basiskurs-haus-schnede-14-20-juli-2025\/\">Jetzt auf Warteliste eintragen<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h3>Inhalte auf diesem Intensivkurs:<\/h3>\n<ul>\n<li>Die Grundlagen der EYEBODY Methode angewandt auf K\u00f6rper, Gehirn und Augen<\/li>\n<li>Die Funktionsweise des Sehsystems<\/li>\n<li>Ein Selbstverst\u00e4ndnis ohne Brille entwickeln<\/li>\n<li>Unterschiede von \u00dcberfokus, Unterfokus und Pr\u00e4senz wahrnehmen und erfahren<\/li>\n<li>Wahrnehmungs\u00fcbungen f\u00fcr Gehirn, Augen und K\u00f6rper<\/li>\n<li>Zusammenh\u00e4nge zwischen Sehthemen und Lebensthemen, Gewohnheiten auf den Pr\u00fcfstand stellen<\/li>\n<li>Br\u00fccken zwischen physischem Sehen und Spiritualit\u00e4t bauen<\/li>\n<li>Gelerntes im Alltag praktisch anwenden, z. B. beim Lesen, im Gehen, bei Computerarbeit u.v.m.<\/li>\n<\/ul>\n<p>Fortgeschrittene EYEBODY-\u00dcbende unterst\u00fctzt der Kurs darin, ihre Erfahrungen zu vertiefen. Alle Teilnehmer werden ihrem Wissenstand und \u00dcbungs-Niveau entsprechend unterwiesen und begleitet. Dazu geh\u00f6rt auch eine kompakte Einzelunterweisung im Laufe der Kurswoche.<\/p>\n<hr \/>\n<p><strong>Der Kurs beinhaltet ein intensives, anspruchsvolles ganzt\u00e4giges Programm.<\/strong> Die erste Einheit ist direkt nach dem Fr\u00fchst\u00fcck, die letzte Einheit des Tages nach dem Abendessen. Zwischen den Einheiten sind kurze, nach dem Mittagessen eine l\u00e4ngere Pause.\u00a0Die Teilnehmer profitieren am meisten durch die Bereitschaft, Gewohntes zu hinterfragen, Widerst\u00e4nde los- und Ver\u00e4nderungen zuzulassen.<\/p>\n<hr \/>\n<h3>Tagungszentrum Schloss Hohenfels:<\/h3>\n<p>Schloss Hohenfels liegt inmitten idyllischer Natur in der N\u00e4he des Bodensees. Das Tagungszentrum ist ein geschichtstr\u00e4chtiger Ort mit modernster Ausstattung, gef\u00fchrt mit dem Bewusstsein, dass innere Arbeit einen nachhaltigen Raum der Stille und des Wohlf\u00fchlens ben\u00f6tigt.<\/p>\n<hr \/>\n<h3>Zimmerbuchung und \u00dcbernachtung:<\/h3>\n<p>Das Schloss bietet \u00a0Einzelzimmer und Doppelzimmer mit eigenem Bad. Das Essen ist vegetarisch\/vegan. Die Produkte sind aus Demeter-Haltung oder zumindest &#8222;bio&#8220;.<\/p>\n<p>Die Buchung des Zimmers wird durch die Kursorganisation erledigt.\u00a0<strong>Die Kosten f\u00fcr 6 \u00dcbernachtungen mit Vollpension betragen je nach Zimmerart und -standard zwischen \u20ac 984 (EZ mit Bad), \u20ac 807 pro Person (geteiltes DZ mit Bad) und \u20ac 1.224 (DZ als EZ).<br \/>\n<\/strong><\/p>\n<p>Kostenanpassungen sind m\u00f6glich.<\/p>\n<hr \/>\n<h3>Kursgeb\u00fchr, Anzahlung und R\u00fccktrittsfristen<\/h3>\n<p>Sie reservieren Ihren Platz mit Zahlung der Kursgeb\u00fchr.<\/p>\n<p>Bei Buchung vor dem 31. M\u00e4rz 2026 reicht zur Reservierung Ihres Seminarplatzes eine Anzahlung in H\u00f6he von 149,- \u20ac. Die Restzahlung in H\u00f6he von 700,- \u20ac ist zum 30. Juni 2026 f\u00e4llig. Bei sp\u00e4terer Zahlung erh\u00f6ht sich der Restbetrag auf 820,- \u20ac, da dann der regul\u00e4re Kurspreis zur Anwendung kommt, und ist bis eine Woche vor Kursbeginn zu bezahlen.<\/p>\n<p>Die Zahlung von Kursgeb\u00fchr bzw. Anzahlung ist innerhalb von 7 Tagen nach Buchung f\u00e4llig. Anderenfalls behalten wir uns vor, den Seminarplatz wieder freizugeben, damit dieser Platz f\u00fcr andere Interessenten zur Verf\u00fcgung steht.<\/p>\n<p>Bei R\u00fccktritt vor 15. Juni 2026 wird die Kursgeb\u00fchr <strong>abzgl. 149,- \u20ac Bearbeitungsgeb\u00fchr<\/strong> erstattet. Bei sp\u00e4terem R\u00fccktritt ist der volle Betrag f\u00fcr Kurs und ggf. auch Unterkunft f\u00e4llig, egal ob Sie k\u00fcndigen, sp\u00e4ter kommen oder fr\u00fcher abreisen. Alle Mitteilungen bed\u00fcrfen der Schriftform und m\u00fcssen vor den genannten Fristen eintreffen. Kann jemand von der etwaigen Warteliste den Kursplatz \u00fcbernehmen, wird die Kursgeb\u00fchr abz\u00fcglich der Bearbeitungsgeb\u00fchr von 149,- \u20ac erstattet.<\/p>\n<hr \/>\n<h3>Datenschutz:<\/h3>\n<p>Ihre\u00a0pers\u00f6nlichen Daten, welche\u00a0w\u00e4hrend des Bestellprozesses angegeben werden m\u00fcssen, verwenden wir ausschlie\u00dflich f\u00fcr die Organisation dieses\u00a0Kurses und f\u00fcr den Versand von weiteren\u00a0Informationen per E-Mail.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h3>Aktuelle Eyebody-Seminare<\/h3>\n<div class=\"seminar-list-wrapper\"><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/6-tage-kurs-niedersachsen-juli-2026\/\">6 Tage-Kurs, Niedersachsen \u2013 Juli 2026<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\"><strong>Ausgebucht! Wir f\u00fchren eine Warteliste.<\/strong> 19. \u2013\u00a0 25. Juli 2026 | Haus Schnede, Salzhausen, Deutschland | Sprache: Deutsch<\/span><\/div><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/6-tage-kurs-hohenfels-juli-2026\/\">6 Tage-Kurs, Schloss Hohenfels \u2013 Juli 2026<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\"><strong>Ausgebucht! Wir f\u00fchren eine Warteliste.<\/strong> 26. Juli \u2013 \u00a01. August 2026 | Schloss Hohenfels, Deutschland | Sprache: Deutsch<\/span><\/div><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/6-tage-kurs-uckermark-august-2026\/\">6 Tage-Kurs, Uckermark \u2013 August 2026<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\"><strong>Ausgebucht! Wir f\u00fchren eine Warteliste.<\/strong> 2. \u2013 \u00a08. August \u00a02026 | Schl\u00fc\u00dfhof Lychen, Deutschland | Sprache: Deutsch<\/span><\/div><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/6-tage-kurs-baden-wuerttemberg-august-2026\/\">6 Tage-Kurs, Baden-W\u00fcrttemberg \u2013 August 2026<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\"><strong>Ausgebucht! Wir f\u00fchren eine Warteliste.<\/strong> 13. \u2013 \u00a019. August 2026 | Tuttlingen\/Schwarzwald, Deutschland | Sprache: Deutsch<\/span><\/div><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/6-tage-kurs-oesterreich-august-2026\/\">6 Tage-Kurs, \u00d6sterreich \u2013 August 2026<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\"><strong>Ausgebucht! Wir f\u00fchren eine Warteliste.<\/strong> 20. \u2013 26. August 2026 | Hotel des Gl\u00fccks, St. Oswald, Nieder\u00f6sterreich | Sprache: Deutsch<\/span><\/div><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/6-day-basis-advanced-retreat-trentino-september-2026\/\">6-Day Basis\/Advanced Retreat, Trentino &#8211; September 2026<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\"><strong>Fully booked. Waiting list.<\/strong> 31 August \u2013 6 September 2026 | Roncegno (Trento), Italy | Language: English + Italian<\/span><\/div><div class=\"listing-item\"><a class=\"title\" href=\"https:\/\/staging.eyebody.com\/de\/new-zealand-2-week-intensive-january-2027\/\">New Zealand 2-week Intensive, January 2027<\/a> <span class=\"excerpt-dash\">-<\/span> <span class=\"excerpt\">8 \u2013 22 January 2027 | Mana Retreat Centre & Coromandel, New Zealand | Language: English<\/span><\/div><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Ausgebucht! Wir f\u00fchren eine Warteliste.<\/strong> 26. Juli \u2013 \u00a01. August 2026 | Schloss Hohenfels, Deutschland | Sprache: Deutsch<\/p>\n","protected":false},"author":5,"featured_media":58758,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[149,146],"tags":[],"class_list":["post-58148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6-tage-basiskurse","category-seminare"],"_links":{"self":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts\/58148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/comments?post=58148"}],"version-history":[{"count":4,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts\/58148\/revisions"}],"predecessor-version":[{"id":65044,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/posts\/58148\/revisions\/65044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/media\/58758"}],"wp:attachment":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/media?parent=58148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/categories?post=58148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/tags?post=58148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}