{"id":39,"date":"2014-03-17T08:11:01","date_gmt":"2014-03-17T06:11:01","guid":{"rendered":"http:\/\/www.eyebody.com\/?page_id=23"},"modified":"2015-07-22T15:48:26","modified_gmt":"2015-07-22T13:48:26","slug":"wie-sehen-funktioniert","status":"publish","type":"page","link":"https:\/\/staging.eyebody.com\/de\/wie-sehen-funktioniert\/","title":{"rendered":"Wie Sehen funktioniert"},"content":{"rendered":"<figure id=\"attachment_7381\" aria-describedby=\"caption-attachment-7381\" style=\"width: 215px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7381\" src=\"https:\/\/www.eyebody.com\/wp-content\/uploads\/2014\/12\/howwesee_Hirn1.jpg\" alt=\"Modell des Gehirns, linke H\u00e4lfte der Sehrinde gr\u00fcn markiert\" width=\"215\" height=\"191\" \/><figcaption id=\"caption-attachment-7381\" class=\"wp-caption-text\">Modell des Gehirns, linke H\u00e4lfte der Sehrinde gr\u00fcn markiert<\/figcaption><\/figure>\n<p>Das Gehirn &#8222;sieht&#8220;&#8230; Lichtwellen, die durch die Hornhaut, das Kammerwasser, die Linse und den Glask\u00f6rper auf die Netzhaut gelangen&#8230; 137 Millionen Photorezeptoren senden die Information \u00fcber die Sehnerven und einen Bereich des Hirnstamms zur Sehrinde. Es ist hier, auf der R\u00fcckseite unseres Sch\u00e4dels, wo wir eigentlich sehen. Von hier werden die Augen und komplexe Funktionen unseres Sehsystems gesteuert.<\/p>\n<figure id=\"attachment_7379\" aria-describedby=\"caption-attachment-7379\" style=\"width: 233px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7379\" src=\"https:\/\/www.eyebody.com\/wp-content\/uploads\/2014\/12\/howwesee_eyeSection.gif\" alt=\"L\u00e4ngsschnitt durch Auge und \u00e4u\u00dfere Augenmuskeln\" width=\"233\" height=\"191\" \/><figcaption id=\"caption-attachment-7379\" class=\"wp-caption-text\">L\u00e4ngsschnitt durch Auge und \u00e4u\u00dfere Augenmuskeln<\/figcaption><\/figure>\n<p>Sehen beruht auf komplexen Mechanismen. Deren reibungsloses und effektives Funktionieren ist ein permanenter Balanceakt. Die Strukturen und Fl\u00fcssigkeiten in den Augen und im Hirnstamm ben\u00f6tigen daf\u00fcr einen Zustand des Gleichgewichts. Nur dann kann das Licht das Auge ungehindert so durchqueren, dass es klares Sehen hervorruft, das gesamte Sehsystem koordiniert und indirekt ein \u00f6konomisches Funktionieren des K\u00f6rpers f\u00f6rdert.<\/p>\n<h3>Wenn etwas schief l\u00e4uft &#8230;<\/h3>\n<p>&#8230; ger\u00e4t diese Balance durcheinander, funktionieren bestimmte Bereiche schlechter oder weniger effizient.\u00a0Ursachen daf\u00fcr sind\u00a0z. B. Ablenkung, \u00e4ngstliche Anspannung oder Abschweifen aus dem gegenw\u00e4rtigen Moment. Wenn eine Person zu viel Kraftaufwand betreibt, um den Blick scharf zu stellen,\u00a0funktioniert die Sehrinde nicht optimal. Bestimmte Bereiche werden dadurch verk\u00fcrzt und \u00fcber einen gewissen Zeitraum angespannt. Daraus kann ein Mangel an Klarheit im Sehen und eine St\u00f6rung in der K\u00f6rperkoordination entstehen.<\/p>\n<h3>Die Wirkung von verordneten Brillen und Kontaktlinsen<\/h3>\n<figure id=\"attachment_7383\" aria-describedby=\"caption-attachment-7383\" style=\"width: 191px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7383\" src=\"https:\/\/www.eyebody.com\/wp-content\/uploads\/2014\/12\/howwesee_visualPathway2.jpg\" alt=\"Querschnitt durch das Gehirn\" width=\"191\" height=\"223\" \/><figcaption id=\"caption-attachment-7383\" class=\"wp-caption-text\">Querschnitt durch das Gehirn<\/figcaption><\/figure>\n<p>Brillen oder Kontaktlinsen b\u00fcndeln das Licht und lenken ein Maximum an Licht auf die Sehgrube, die Stelle des sch\u00e4rfsten Sehens auf der Netzhaut (Fovea centralis). Dort befinden sich jedoch nur ca. 5% der Sinneszellen.<\/p>\n<p>So werden die peripheren Bereiche der Netzhaut und damit auch der Sehrinde nicht wirklich benutzt. Genauso wenig muss das Auge sich bewegen oder etwas &#8222;arbeiten&#8220;. Oft verursacht dies eine weitere Schw\u00e4chung der Augen und damit die Verschreibung immer st\u00e4rkerer Gl\u00e4ser bzw. Linsen.<\/p>\n<p>Brillen oder Kontaktlinsen verursachen nicht nur, dass die Augen &#8222;erstarren&#8220;, sondern f\u00f6rdern auch ein Zusammensacken der Haltung. Dies wiederum beeintr\u00e4chtigt den Atem und verursacht zunehmende Nacken- und R\u00fcckenschmerzen.<\/p>\n<p>Die Grunwald EyeBody-Methode<sup>\u00ae<\/sup> hilft Ihnen, die Gewohnheit des Brille- bzw. Linsentragens auf nat\u00fcrliche Weise zu durchbrechen. Sie k\u00f6nnen au\u00dferdem lernen, sich mit gr\u00f6\u00dferer Freiheit und Leichtigkeit zu bewegen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Gehirn &#8222;sieht&#8220;&#8230; Lichtwellen, die durch die Hornhaut, das Kammerwasser, die Linse und den Glask\u00f6rper auf die Netzhaut gelangen&#8230; 137 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":142,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-39","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/pages\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":4,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":7387,"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/pages\/39\/revisions\/7387"}],"wp:attachment":[{"href":"https:\/\/staging.eyebody.com\/de\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}